﻿{"id":38925,"date":"2026-05-13T10:04:36","date_gmt":"2026-05-13T13:04:36","guid":{"rendered":"https:\/\/ifbaiano.edu.br\/portal\/?p=38925"},"modified":"2026-05-13T10:06:06","modified_gmt":"2026-05-13T13:06:06","slug":"vagas-abertas-para-pos-graduacao-com-enfase-em-cacau-e-chocolate-no-campus-urucuca","status":"publish","type":"post","link":"https:\/\/ifbaiano.edu.br\/portal\/blog\/vagas-abertas-para-pos-graduacao-com-enfase-em-cacau-e-chocolate-no-campus-urucuca\/","title":{"rendered":"Vagas abertas para p\u00f3s-gradua\u00e7\u00e3o com \u00eanfase em cacau e chocolate no Campus Uru\u00e7uca"},"content":{"rendered":"\n<p>O Instituto Federal Baiano (IF Baiano) publicou edital de sele\u00e7\u00e3o para o provimento de 9 vagas remanescentes do curso de p\u00f3s-gradua\u00e7\u00e3o <em>Lato Sensu<\/em> em <strong>Ci\u00eancia e Tecnologia de Alimentos com \u00eanfase em Cacau e Chocolat<\/strong>e, oferecido na modalidade Educa\u00e7\u00e3o a Dist\u00e2ncia (Ead) pelo Campus Uru\u00e7uca.<\/p>\n\n\n\n<p>O per\u00edodo para realizar inscri\u00e7\u00e3o ser\u00e1 de <strong>15 e 18 de maio<\/strong>. Os interessados devem encaminhar a documenta\u00e7\u00e3o exigida, conforme orienta\u00e7\u00f5es do edital, para o e-mail <a href=\"mailto:pos.alim@urucuca.ifbaiano.edu.br\">pos.alim@urucuca.ifbaiano.edu.br<\/a>.<\/p>\n\n\n\n<p>O curso \u00e9 destinado a profissionais de n\u00edvel superior que trabalham ou possuem interesse na cadeia de valor do cacau e chocolate. Portanto, para ingressar no curso, \u00e9 necess\u00e1rio ser portador de diploma de n\u00edvel superior, reconhecido pelo Minist\u00e9rio da Educa\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sele\u00e7\u00e3o<\/strong>&nbsp;<\/h3>\n\n\n\n<p>A sele\u00e7\u00e3o dos candidatos ser\u00e1 realizada em etapa \u00fanica, de car\u00e1ter classificat\u00f3rio e eliminat\u00f3rio, por meio de entrevista individual. A publica\u00e7\u00e3o do resultado final est\u00e1 prevista para 14 de maio, enquanto a matr\u00edcula ocorrer\u00e1 no per\u00edodo de 25 a 28 de maio de 2026.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sobre a forma\u00e7\u00e3o&nbsp;<\/strong><\/h3>\n\n\n\n<p>O curso de especializa\u00e7\u00e3o em Ci\u00eancia e Tecnologia de Alimentos com \u00eanfase em Cacau e Chocolate \u00e9 ofertado na modalidade EaD e tem como objetivo capacitar profissionais t\u00e9cnicos e pesquisadores vinculados \u00e0 administra\u00e7\u00e3o p\u00fablica ou privada e profissionais liberais interessados na tem\u00e1tica da ci\u00eancia e tecnologia de alimentos, com \u00eanfase em cacau e chocolate, por meio da compreens\u00e3o das cadeias de valor dos produtos regionais, sobretudo a cadeia de valor do cacau\/chocolate e suas peculiaridades.&nbsp;<\/p>\n\n\n\n<p>Durante a forma\u00e7\u00e3o, tamb\u00e9m s\u00e3o trabalhados temas fundamentais como sustentabilidade, agroecologia, agricultura familiar, inova\u00e7\u00f5es tecnol\u00f3gicas e desenvolvimento territorial.&nbsp;<\/p>\n\n\n\n<p>Com uma carga hor\u00e1ria de 360h, distribu\u00eddas em 11 componentes curriculares e dura\u00e7\u00e3o m\u00ednima de 12 meses, o curso prop\u00f5e, al\u00e9m das aulas online, atividades pr\u00e1ticas, viv\u00eancias e visitas t\u00e9cnicas que poder\u00e3o ser presenciais no IF Baiano, <em>Campus<\/em> Uru\u00e7uca, ou em outros espa\u00e7os previamente comunicados pela coordena\u00e7\u00e3o.<\/p>\n\n\n\n<p>Mais <a href=\"https:\/\/www.ifbaiano.edu.br\/unidades\/urucuca\/ciencia-e-tecnologia-de-alimentos-enfase-em-cacau-e-chocolate\/\" target=\"_blank\" rel=\"noreferrer noopener\">informa\u00e7\u00f5es<\/a> sobre o curso.&nbsp;<\/p>\n\n\n\n<p>Acesse o edital e acompanhe os resultados da sele\u00e7\u00e3o <a rel=\"noreferrer noopener\" href=\"https:\/\/concurso.ifbaiano.edu.br\/portal\/vagas-remanescentes-pos-ciencia-tecnologia-de-alimentos-urucuca-2026\/\" target=\"_blank\"><strong>nesta p\u00e1gina<\/strong><\/a>.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Curso de especializa\u00e7\u00e3o \u00e9 oferecido na modalidade EaD com possibilidade de atividades presenciais. <\/p>\n","protected":false},"author":7,"featured_media":38927,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,5,10],"tags":[35,97,79],"_links":{"self":[{"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/posts\/38925"}],"collection":[{"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/comments?post=38925"}],"version-history":[{"count":2,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/posts\/38925\/revisions"}],"predecessor-version":[{"id":38929,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/posts\/38925\/revisions\/38929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/media\/38927"}],"wp:attachment":[{"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/media?parent=38925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/categories?post=38925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/tags?post=38925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}