﻿{"id":30452,"date":"2024-03-15T11:20:01","date_gmt":"2024-03-15T14:20:01","guid":{"rendered":"https:\/\/ifbaiano.edu.br\/portal\/?p=30452"},"modified":"2026-07-07T10:08:44","modified_gmt":"2026-07-07T13:08:44","slug":"campus-urucuca-abre-selecao-para-professor-substituto-em-administracao","status":"publish","type":"post","link":"https:\/\/ifbaiano.edu.br\/portal\/blog\/campus-urucuca-abre-selecao-para-professor-substituto-em-administracao\/","title":{"rendered":"Campus Uru\u00e7uca abre sele\u00e7\u00e3o para Professor Substituto em Administra\u00e7\u00e3o"},"content":{"rendered":"\n<p>O Instituto Federal Baiano (IF Baiano) Campus Uru\u00e7uca est\u00e1 ofertando uma vaga para o Processo Seletivo Simplificado para a contrata\u00e7\u00e3o de Professor Substituto na \u00e1rea de Administra\u00e7\u00e3o, da categoria funcional de professor de Ensino B\u00e1sico, T\u00e9cnico e Tecnol\u00f3gico, Classe DI, N\u00edvel 01.<\/p>\n\n\n\n<p>As inscri\u00e7\u00f5es ser\u00e3o realizadas entre os dias 18 e 24 de mar\u00e7o de 2024, exclusivamente, atrav\u00e9s do endere\u00e7o de e-mail: selecao.professor@urucuca.ifbaiano.edu.br. Para efetivar a inscri\u00e7\u00e3o, o candidato precisa preencher e assinar a ficha de inscri\u00e7\u00e3o dispon\u00edvel no Anexo I do <a href=\"https:\/\/concurso.ifbaiano.edu.br\/portal\/substituto-urucuca-marco-2024\/wp-content\/uploads\/sites\/969\/2024\/03\/Edital-no-49-de-13-de-marc%CC%A7o-de-2024-PROCESSO-SELETIVO-SIMPLIFICADO-PARA-CONTRATAC%CC%A7A%CC%83O-DE-PROFESSOR-SUBSTITUTO-CAMPUS-URUC%CC%A7UCA.pdf\"><u>edital<\/u><\/a>, al\u00e9m de anexar os documentos exigidos no item 5.2.<\/p>\n\n\n\n<p>O processo seletivo visa preencher 1 vaga no cargo de Professor Substituto, com jornada de trabalho de 20 ou 40 horas semanais, a ser definida de acordo com a necessidade do Campus. O contrato ter\u00e1 dura\u00e7\u00e3o de at\u00e9 12 meses, com possibilidade de prorroga\u00e7\u00e3o por igual per\u00edodo.<\/p>\n\n\n\n<p>Para concorrer \u00e0 vaga, o candidato precisa ter Bacharelado em Administra\u00e7\u00e3o e Mestrado em Administra\u00e7\u00e3o ou \u00e1reas afins. A sele\u00e7\u00e3o ser\u00e1 composta por duas etapas: Prova de Desempenho Did\u00e1tico (eliminat\u00f3ria e classificat\u00f3ria) e Prova de T\u00edtulos (classificat\u00f3ria).<\/p>\n\n\n\n<p>A Prova de Desempenho Did\u00e1tico ser\u00e1 realizada de forma presencial, no per\u00edodo de 3 a 4 de abril de 2024, no Campus Uru\u00e7uca, situado \u00e0 Rua Dr. Jo\u00e3o Nascimento &#8211; S\/N &#8211; Centro &#8211; Uru\u00e7uca &#8211; BA &#8211; CEP: 45680-000. J\u00e1 a Prova de T\u00edtulos ser\u00e1 realizada apenas para os candidatos classificados na primeira etapa.<\/p>\n\n\n\n<p>O resultado preliminar do processo seletivo estar\u00e1 dispon\u00edvel no site do IF Baiano<a href=\"https:\/\/concurso.ifbaiano.edu.br\/\"> <\/a><a href=\"https:\/\/concurso.ifbaiano.edu.br\/\"><u>https:\/\/concurso.ifbaiano.edu.br\/<\/u><\/a>.<\/p>\n\n\n\n<p>Em caso de d\u00favidas, os candidatos podem entrar em contato atrav\u00e9s do e-mail: <a href=\"mailto:selecao.professor@urucuca.ifbaiano.edu.br\"><u>selecao.professor@urucuca.ifbaiano.edu.br<\/u><\/a> ou diretamente no IF Baiano Campus Uru\u00e7uca, situado na Rua Dr. Jo\u00e3o Nascimento, S\/N, Centro, Uru\u00e7uca-BA.<\/p>\n\n\n\n<p>Para mais informa\u00e7\u00f5es, consulte o <a href=\"https:\/\/concurso.ifbaiano.edu.br\/portal\/substituto-urucuca-marco-2024\/wp-content\/uploads\/sites\/969\/2024\/03\/Edital-no-49-de-13-de-marc%CC%A7o-de-2024-PROCESSO-SELETIVO-SIMPLIFICADO-PARA-CONTRATAC%CC%A7A%CC%83O-DE-PROFESSOR-SUBSTITUTO-CAMPUS-URUC%CC%A7UCA.pdf\"><u>edital <\/u><\/a>completo dispon\u00edvel no site do IF Baiano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto Federal Baiano (IF Baiano) Campus Uru\u00e7uca est\u00e1 ofertando uma vaga para o Processo Seletivo Simplificado para a contrata\u00e7\u00e3o de Professor Substituto na \u00e1rea de Administra\u00e7\u00e3o, da categoria funcional de professor de Ensino B\u00e1sico, T\u00e9cnico e Tecnol\u00f3gico, Classe DI, N\u00edvel 01. As inscri\u00e7\u00f5es ser\u00e3o realizadas entre os dias 18 e 24 de mar\u00e7o de [&hellip;]<\/p>\n","protected":false},"author":96,"featured_media":29891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,3,5,10],"tags":[40,655],"_links":{"self":[{"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/posts\/30452"}],"collection":[{"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/users\/96"}],"replies":[{"embeddable":true,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/comments?post=30452"}],"version-history":[{"count":1,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/posts\/30452\/revisions"}],"predecessor-version":[{"id":30453,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/posts\/30452\/revisions\/30453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/media\/29891"}],"wp:attachment":[{"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/media?parent=30452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/categories?post=30452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/tags?post=30452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}