﻿{"id":23466,"date":"2022-05-23T23:42:29","date_gmt":"2022-05-24T02:42:29","guid":{"rendered":"https:\/\/ifbaiano.edu.br\/portal\/?p=23466"},"modified":"2026-07-07T11:27:20","modified_gmt":"2026-07-07T14:27:20","slug":"campus-alagoinhas-abre-inscricoes-para-cursos-integrados-e-subsequentes","status":"publish","type":"post","link":"https:\/\/ifbaiano.edu.br\/portal\/blog\/campus-alagoinhas-abre-inscricoes-para-cursos-integrados-e-subsequentes\/","title":{"rendered":"Campus Alagoinhas abre inscri\u00e7\u00f5es para cursos Integrados e Subsequentes"},"content":{"rendered":"\n<p>O <em>campus <\/em>do Instituto Federal Baiano (IF Baiano) em Alagoinhas est\u00e1 com sele\u00e7\u00e3o aberta para o preenchimento de 270 vagas em cursos t\u00e9cnicos, nas modalidades <a href=\"https:\/\/opinanovo.ifbaiano.edu.br\/index.php\/537753?lang=pt-BR\">Integrada<\/a> e <a href=\"https:\/\/opinanovo.ifbaiano.edu.br\/index.php\/552138?lang=pt-BR\">Subsequente<\/a> ao ensino m\u00e9dio. As inscri\u00e7\u00f5es s\u00e3o gratuitas e podem ser realizadas pela internet. O per\u00edodo de inscri\u00e7\u00e3o vai de 24 de maio at\u00e9 22 de junho.<\/p>\n\n\n\n<p>Os cursos Integrados ofertados s\u00e3o de T\u00e9cnico em Agroind\u00fastria (80 vagas), T\u00e9cnico em Agroecologia (80 vagas) e T\u00e9cnico em Inform\u00e1tica (30 vagas). Podem se inscrever na sele\u00e7\u00e3o pessoas que conclu\u00edram ou concluem at\u00e9 a data da matr\u00edcula o Ensino Fundamental II (9\u00ba ano).<\/p>\n\n\n\n<p>O <em>campus<\/em> tamb\u00e9m oferta o curso T\u00e9cnico em Agroind\u00fastria na modalidade Subsequente para quem j\u00e1 concluiu o ensino m\u00e9dio. S\u00e3o 40 vagas para a turma matutina e 40 para a noturna.<\/p>\n\n\n\n<p>Para se inscrever nos Processos Seletivos, os candidatos devem realizar os seguintes passos: acessar o sistema on-line de inscri\u00e7\u00f5es de cada Processo Seletivo, que ser\u00e1 disponibilizado<a href=\"https:\/\/concurso.ifbaiano.edu.br\/portal\/ingresso-de-estudantes-2022\/\"> no site do IF Baiano<\/a> na data de abertura das inscri\u00e7\u00f5es; preencher formul\u00e1rio com dados pessoais e socioecon\u00f4micos; informar a escolaridade e onde cursou o Ensino Fundamental; selecionar o curso para o qual deseja se inscrever como 1\u00aa op\u00e7\u00e3o e um curso diferente para se inscrever como 2\u00aa op\u00e7\u00e3o; informar as notas das m\u00e9dias finais do Hist\u00f3rico Escolar das disciplinas L\u00edngua Portuguesa, Matem\u00e1tica, Hist\u00f3ria, Ci\u00eancias e Geografia do 8\u00ba ano do Ensino Fundamental II (na inscri\u00e7\u00e3o para cursos Integrados); selecionar a reserva de vagas que deseja concorrer; inserir arquivo, preferencialmente, em PDF dos documentos listados pelo edital.<\/p>\n\n\n\n<p>Os cursos de n\u00edvel m\u00e9dio e t\u00e9cnico do IF Baiano reservam 75% das vagas para cotas em diferentes categorias de a\u00e7\u00f5es afirmativas e 25% para ampla concorr\u00eancia.<\/p>\n\n\n\n<p><strong>Sele\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>Na sele\u00e7\u00e3o para cursos Integrados, a classifica\u00e7\u00e3o de candidatos ser\u00e1 definida a partir da M\u00e9dia Final resultante das m\u00e9dias dos componentes curriculares L\u00edngua Portuguesa, Matem\u00e1tica, Hist\u00f3ria, Ci\u00eancias e Geografia do 8\u00ba ano do Ensino Fundamental, atrav\u00e9s de an\u00e1lise do hist\u00f3rico escolar anexado \u00e0 documenta\u00e7\u00e3o no ato de inscri\u00e7\u00e3o. J\u00e1 na sele\u00e7\u00e3o para cursos Subsequentes, o crit\u00e9rio de classifica\u00e7\u00e3o \u00e9 a ordem de inscri\u00e7\u00f5es.<\/p>\n\n\n\n<p>O resultado final ser\u00e1 divulgado no dia 15 de julho no portal do IF Baiano.<\/p>\n\n\n\n<p>O ingresso de estudantes nos cursos da Educa\u00e7\u00e3o Profissional T\u00e9cnica de N\u00edvel M\u00e9dio em 2022 est\u00e1 com novo formato. Os 14 <em>campi<\/em> do Instituto Federal Baiano lan\u00e7am seus editais, com cronogramas pr\u00f3prios, para o ingresso em suas localidades. Para acompanhar esse e outros processos seletivos, acesse a p\u00e1gina do<a href=\"https:\/\/concurso.ifbaiano.edu.br\/portal\/ingresso-de-estudantes-2022\/\"> Processo de Ingresso de Estudantes de 2022.<\/a><\/p>\n\n\n\n<p>Em caso de d\u00favida, basta entrar em contato com a comiss\u00e3o do Prosel atrav\u00e9s do e-mail <a href=\"mailto:prosel@alagoinhas.ifbaiano.edu.br\">prosel@alagoinhas.ifbaiano.edu.br<\/a>.<\/p>\n\n\n\n<p><strong>Confira os editais:<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/concurso.ifbaiano.edu.br\/portal\/ingresso-integrado-alagoinhas-maio-2022\/wp-content\/uploads\/sites\/597\/2022\/05\/Edital-01-Integrado.pdf\">Edital dos cursos Integrados<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/concurso.ifbaiano.edu.br\/portal\/ingresso-subsequente-alagoinhas-maio-2022\/wp-content\/uploads\/sites\/598\/2022\/05\/Edital-02-Subsequente.pdf\">Edital do curso Subsequente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inscri\u00e7\u00f5es iniciam nesta ter\u00e7a-feira (24) e v\u00e3o at\u00e9 o dia 22 de junho para preenchimento de 270 vagas<\/p>\n","protected":false},"author":96,"featured_media":22335,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,5,10],"tags":[72,64,471,289],"_links":{"self":[{"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/posts\/23466"}],"collection":[{"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/users\/96"}],"replies":[{"embeddable":true,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/comments?post=23466"}],"version-history":[{"count":4,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/posts\/23466\/revisions"}],"predecessor-version":[{"id":23476,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/posts\/23466\/revisions\/23476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/media\/22335"}],"wp:attachment":[{"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/media?parent=23466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/categories?post=23466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ifbaiano.edu.br\/portal\/wp-json\/wp\/v2\/tags?post=23466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}